{"id":1884,"date":"2025-07-31T11:40:01","date_gmt":"2025-07-31T09:40:01","guid":{"rendered":"http:\/\/dev.alcomnet.com\/cosimad\/?page_id=1884"},"modified":"2025-07-31T12:36:42","modified_gmt":"2025-07-31T10:36:42","slug":"product-ranges","status":"publish","type":"page","link":"http:\/\/dev.alcomnet.com\/cosimad\/dev\/product-ranges\/","title":{"rendered":"Product ranges"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1884\" class=\"elementor elementor-1884\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2231f0a e-flex e-con-boxed e-con e-parent\" data-id=\"2231f0a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0454ec0 elementor-widget elementor-widget-page-title\" data-id=\"0454ec0\" data-element_type=\"widget\" data-widget_type=\"page-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n\t\t<div class=\"hfe-page-title hfe-page-title-wrapper elementor-widget-heading\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/dev.alcomnet.com\/cosimad\">\n\t\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\n\t\t\t\t\t\t\t\t\n\t\t\t\tProduct ranges  \n\t\t\t<\/h1 > \n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86153db elementor-widget elementor-widget-eael-breadcrumbs\" data-id=\"86153db\" data-element_type=\"widget\" data-widget_type=\"eael-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eael-breadcrumbs\">\n\t\t\t<div class=\"eael-breadcrumbs__content\"><a href=\"http:\/\/dev.alcomnet.com\/cosimad\">Accueil<\/a> <span class=\"eael-breadcrumb-separator\">\/<\/span> <span class = \"eael-current\">Page<\/span><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e6f24a e-flex e-con-boxed e-con e-parent\" data-id=\"3e6f24a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8f51d8 elementor-widget elementor-widget-shortcode\" data-id=\"d8f51d8\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"liste-categories-produits\"><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/boxes-kits\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Coffrets-Trousses.jpg\" alt=\"Boxes &amp; Kits\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"boxes-kits\">Boxes &amp; Kits<\/h2><p>Discover our selection of elegant, practical and gift-ready boxes and cases. Perfect for organizing your essentials or pleasing loved ones in style.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/boxes-kits\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/coffrets-trousses\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/12\/COFFRET-DOLLE-vertical.jpg\" alt=\"Coffrets &amp; Trousses\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"coffrets-trousses\">Coffrets &amp; Trousses<\/h2><p>D\u00e9couvrez notre s\u00e9lection de coffrets et trousses \u00e9l\u00e9gants, pratiques et pr\u00eats \u00e0 offrir. Parfaits pour organiser vos essentiels ou faire plaisir \u00e0 vos proches avec style.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/coffrets-trousses\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/coiffants-gels\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/12\/GEL-WAX.jpg\" alt=\"Coiffants &amp; Gels\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"coiffants-gels\">Coiffants &amp; Gels<\/h2><p>Ma\u00eetrisez chaque m\u00e8che avec notre gamme de coiffants et gels : pour une tenue parfaite, un style ma\u00eetris\u00e9 et une finition impeccable au quotidien.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/coiffants-gels\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/cream-body-care\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Soins-Cremes-Corps.png\" alt=\"Cream &amp; Body Care\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"cream-body-care\">Cream &amp; Body Care<\/h2><p>Light, distinctive fragrances to assert your identity every day<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/cream-body-care\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/deodorants-en\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Deodorants.png\" alt=\"Deodorants\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"deodorants\">Deodorants<\/h2><p>Invisible protection, a breath of pure lightness Our deodorants take care of your skin, without compromising on softness.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/deodorants-en\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/deodorants-fr\/\" class=\"bloc-categorie-produit\"><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"deodorants-vaporisateur-spray\">D\u00e9odorants Vaporisateur ( Spray )<\/h2><p>Une protection invisible, un vent de l\u00e9g\u00e8ret\u00e9 pure Nos d\u00e9odorants prennent soin de votre peau, sans compromis sur la douceur.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/deodorants-fr\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/hygiene-depilation\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/12\/Savon-liquide-vertical.jpg\" alt=\"Hygi\u00e8ne &amp; D\u00e9pilation\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"hygiene-depilation\">Hygi\u00e8ne &amp; D\u00e9pilation<\/h2><p>Prenez soin de votre peau au quotidien avec notre s\u00e9lection de produits d\u2019hygi\u00e8ne et de d\u00e9pilation : efficacit\u00e9, douceur et confort pour une sensation de fra\u00eecheur durable.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/hygiene-depilation\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/hygiene-depilation-en\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Hygiene-Depilation.jpg\" alt=\"Hygiene &amp; Depilation\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"hygiene-depilation\">Hygiene &amp; Depilation<\/h2><p>Take care of your skin every day with our selection of hygiene and depilatory products: effective, gentle and comfortable for a long-lasting sensation of freshness.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/hygiene-depilation-en\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/parfums-eau-de-toilette\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/12\/EDT-FEMME-vertical.jpg\" alt=\"Parfums &amp; Eau de toilette\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"parfums-eau-de-toilette\">Parfums &amp; Eau de toilette<\/h2><p>Un soin nettoyant doux qui respecte l\u2019\u00e9quilibre de votre peau. Sa formule d\u00e9licate purifie en profondeur tout en pr\u00e9servant l\u2019hydratation, de votre peau<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/parfums-eau-de-toilette\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/parfums-eau-de-toilette-en\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Parfums-Eau-de-toilette.png\" alt=\"Parfums &amp; Eau de toilette\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"parfums-eau-de-toilette\">Parfums &amp; Eau de toilette<\/h2><p>A gentle cleanser that respects your skin&#039;s balance. Its delicate formula deeply purifies while preserving your skin&#039;s moisture.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/parfums-eau-de-toilette-en\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/roll-on-stick\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/12\/ROLL-ON-not-selected.jpg\" alt=\"Roll-on &amp; Stick\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"roll-on-stick\">Roll-on &amp; Stick<\/h2><p>Pratiques et efficaces, nos sticks Dolle offrent une application cibl\u00e9e, hygi\u00e9nique et nomade. Pour une peau nette, prot\u00e9g\u00e9e et soign\u00e9e, o\u00f9 que vous soyez.\r\n<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/roll-on-stick\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/roll-on-stick-en\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Roll-on-Stick.png\" alt=\"Roll-on &amp; Stick\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"roll-on-stick\">Roll-on &amp; Stick<\/h2><p>Practical and effective, our Dolle sticks offer targeted, hygienic, on-the-go application. For clean, protected and well-cared-for skin, wherever you are.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/roll-on-stick-en\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/soins-capillaires\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/12\/SERUM-vertical.jpg\" alt=\"Soins Capillaires\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"soins-capillaires\">Soins Capillaires<\/h2><p>Ciblez vos besoins particuliers avec notre gamme de soins sp\u00e9cifiques : des formules expertes pour traiter, apaiser et sublimer chaque type de peau ou de cheveux.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/soins-capillaires\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/soins-cremes-corps\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/12\/Creme-vertical.jpg\" alt=\"Soins Cr\u00e8mes &amp; Corps\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"soins-cremes-corps\">Soins Cr\u00e8mes &amp; Corps<\/h2><p>Parfums l\u00e9gers et marquants, pour affirmer votre identit\u00e9 au quotidien\r\n<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/categorie-produit\/soins-cremes-corps\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/specific-care\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Soins-Specifiques.jpg\" alt=\"Specific Care\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"specific-care\">Specific Care<\/h2><p>Target your specific needs with our range of special care products: expert formulas to treat, soothe and enhance every type of skin or hair.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/specific-care\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/styling-gels\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Coiffants-Gels-1.jpg\" alt=\"Styling &amp; Gels\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"styling-gels\">Styling &amp; Gels<\/h2><p>Master every strand with our range of stylers and gels: for perfect hold, controlled styling and a flawless finish every day.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev\/categorie-produit\/styling-gels\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d8%a7%d9%84%d8%ad%d9%82%d8%a7%d8%a6%d8%a8-%d9%88%d8%a7%d9%84%d8%a3%d8%b7%d9%82%d9%85\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Coffrets-Trousses.jpg\" alt=\"\u0627\u0644\u062d\u0642\u0627\u0626\u0628 \u0648\u0627\u0644\u0623\u0637\u0642\u0645\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"%d8%a7%d9%84%d8%ad%d9%82%d8%a7%d8%a6%d8%a8-%d9%88%d8%a7%d9%84%d8%a3%d8%b7%d9%82%d9%85\">\u0627\u0644\u062d\u0642\u0627\u0626\u0628 \u0648\u0627\u0644\u0623\u0637\u0642\u0645<\/h2><p>\u0627\u0643\u062a\u0634\u0641 \u0645\u062c\u0645\u0648\u0639\u062a\u0646\u0627 \u0627\u0644\u0645\u062e\u062a\u0627\u0631\u0629 \u0645\u0646 \u0627\u0644\u0635\u0646\u0627\u062f\u064a\u0642 \u0648\u0627\u0644\u062d\u0642\u0627\u0626\u0628 \u0627\u0644\u0623\u0646\u064a\u0642\u0629 \u0648\u0627\u0644\u0639\u0645\u0644\u064a\u0629 \u0648\u0627\u0644\u062c\u0627\u0647\u0632\u0629 \u0644\u0644\u0647\u062f\u0627\u064a\u0627. \u0645\u062b\u0627\u0644\u064a\u0629 \u0644\u062a\u0646\u0638\u064a\u0645 \u0645\u0633\u062a\u0644\u0632\u0645\u0627\u062a\u0643 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629 \u0623\u0648 \u0644\u062a\u0642\u062f\u064a\u0645\u0647\u0627 \u0644\u0623\u062d\u0628\u0627\u0626\u0643 \u0628\u0623\u0646\u0627\u0642\u0629.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d8%a7%d9%84%d8%ad%d9%82%d8%a7%d8%a6%d8%a8-%d9%88%d8%a7%d9%84%d8%a3%d8%b7%d9%82%d9%85\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d8%a7%d9%84%d9%86%d8%b8%d8%a7%d9%81%d8%a9-%d9%88%d8%a5%d8%b2%d8%a7%d9%84%d8%a9-%d8%a7%d9%84%d8%b4%d8%b9%d8%b1\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Hygiene-Depilation.jpg\" alt=\"\u0627\u0644\u0646\u0638\u0627\u0641\u0629 \u0648\u0625\u0632\u0627\u0644\u0629 \u0627\u0644\u0634\u0639\u0631\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"%d8%a7%d9%84%d9%86%d8%b8%d8%a7%d9%81%d8%a9-%d9%88%d8%a5%d8%b2%d8%a7%d9%84%d8%a9-%d8%a7%d9%84%d8%b4%d8%b9%d8%b1\">\u0627\u0644\u0646\u0638\u0627\u0641\u0629 \u0648\u0625\u0632\u0627\u0644\u0629 \u0627\u0644\u0634\u0639\u0631<\/h2><p>\u0627\u0639\u062a\u0646\u064a \u0628\u0628\u0634\u0631\u062a\u0643 \u0643\u0644 \u064a\u0648\u0645 \u0645\u0639 \u0645\u062c\u0645\u0648\u0639\u062a\u0646\u0627 \u0627\u0644\u0645\u062e\u062a\u0627\u0631\u0629 \u0645\u0646 \u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u0646\u0638\u0627\u0641\u0629 \u0648\u0625\u0632\u0627\u0644\u0629 \u0627\u0644\u0634\u0639\u0631: \u0641\u0639\u0627\u0644\u0629 \u0648\u0644\u0637\u064a\u0641\u0629 \u0648\u0645\u0631\u064a\u062d\u0629 \u0644\u0625\u062d\u0633\u0627\u0633 \u0628\u0627\u0644\u0627\u0646\u062a\u0639\u0627\u0634 \u064a\u062f\u0648\u0645 \u0637\u0648\u064a\u0644\u0627\u064b.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d8%a7%d9%84%d9%86%d8%b8%d8%a7%d9%81%d8%a9-%d9%88%d8%a5%d8%b2%d8%a7%d9%84%d8%a9-%d8%a7%d9%84%d8%b4%d8%b9%d8%b1\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d8%aa%d8%b5%d9%81%d9%8a%d9%81-%d8%a7%d9%84%d8%b4%d8%b9%d8%b1-%d9%88%d8%a7%d9%84%d8%ac%d9%84\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Coiffants-Gels-1.jpg\" alt=\"\u062a\u0635\u0641\u064a\u0641 \u0627\u0644\u0634\u0639\u0631 \u0648\u0627\u0644\u062c\u0644\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"%d8%aa%d8%b5%d9%81%d9%8a%d9%81-%d8%a7%d9%84%d8%b4%d8%b9%d8%b1-%d9%88%d8%a7%d9%84%d8%ac%d9%84\">\u062a\u0635\u0641\u064a\u0641 \u0627\u0644\u0634\u0639\u0631 \u0648\u0627\u0644\u062c\u0644<\/h2><p>\u062a\u062d\u0643\u0651\u0645\u064a \u0641\u064a \u0643\u0644 \u062e\u0635\u0644\u0629 \u0645\u0639 \u0645\u062c\u0645\u0648\u0639\u062a\u0646\u0627 \u0645\u0646 \u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u062a\u0635\u0641\u064a\u0641 \u0648\u0627\u0644\u062c\u0644: \u0644\u062a\u062b\u0628\u064a\u062a \u0645\u062b\u0627\u0644\u064a \u0648\u062a\u0633\u0631\u064a\u062d \u0645\u062a\u062d\u0643\u0645 \u0641\u064a\u0647 \u0648\u0644\u0645\u0633\u0629 \u0646\u0647\u0627\u0626\u064a\u0629 \u062e\u0627\u0644\u064a\u0629 \u0645\u0646 \u0627\u0644\u0639\u064a\u0648\u0628 \u0643\u0644 \u064a\u0648\u0645.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d8%aa%d8%b5%d9%81%d9%8a%d9%81-%d8%a7%d9%84%d8%b4%d8%b9%d8%b1-%d9%88%d8%a7%d9%84%d8%ac%d9%84\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d8%b9%d8%b7%d8%b1-%d9%88-%d9%85%d8%a7%d8%a1-%d8%b9%d8%b7%d8%b1-%d8%ae%d9%81%d9%8a%d9%81\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Parfums-Eau-de-toilette.png\" alt=\"\u0639\u0637\u0631 \u0648 \u0645\u0627\u0621 \u0639\u0637\u0631 \u062e\u0641\u064a\u0641\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"%d8%b9%d8%b7%d8%b1-%d9%88-%d9%85%d8%a7%d8%a1-%d8%b9%d8%b7%d8%b1-%d8%ae%d9%81%d9%8a%d9%81\">\u0639\u0637\u0631 \u0648 \u0645\u0627\u0621 \u0639\u0637\u0631 \u062e\u0641\u064a\u0641<\/h2><p>\u0645\u0646\u0638\u0641 \u0644\u0637\u064a\u0641 \u064a\u062d\u062a\u0631\u0645 \u062a\u0648\u0627\u0632\u0646 \u0628\u0634\u0631\u062a\u0643. \u062a\u0646\u0642\u064a \u062a\u0631\u0643\u064a\u0628\u062a\u0647 \u0627\u0644\u0631\u0642\u064a\u0642\u0629 \u0628\u0639\u0645\u0642 \u0645\u0639 \u0627\u0644\u062d\u0641\u0627\u0638 \u0639\u0644\u0649 \u0631\u0637\u0648\u0628\u0629 \u0628\u0634\u0631\u062a\u0643.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d8%b9%d8%b7%d8%b1-%d9%88-%d9%85%d8%a7%d8%a1-%d8%b9%d8%b7%d8%b1-%d8%ae%d9%81%d9%8a%d9%81\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d8%b9%d9%86%d8%a7%d9%8a%d8%a9-%d8%a8%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-%d9%88%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%ac%d8%b3%d9%85\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Soins-Cremes-Corps.png\" alt=\"\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629 \u0648\u0627\u0644\u0643\u0631\u064a\u0645\u0627\u062a \u0648\u0627\u0644\u062c\u0633\u0645\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"%d8%b9%d9%86%d8%a7%d9%8a%d8%a9-%d8%a8%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-%d9%88%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%ac%d8%b3%d9%85\">\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0628\u0634\u0631\u0629 \u0648\u0627\u0644\u0643\u0631\u064a\u0645\u0627\u062a \u0648\u0627\u0644\u062c\u0633\u0645<\/h2><p>\u0639\u0637\u0648\u0631 \u062e\u0641\u064a\u0641\u0629 \u0648\u062c\u0630\u0627\u0628\u0629 \u0644\u062a\u0623\u0643\u064a\u062f \u0647\u0648\u064a\u062a\u0643 \u0643\u0644 \u064a\u0648\u0645<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d8%b9%d9%86%d8%a7%d9%8a%d8%a9-%d8%a8%d8%a7%d9%84%d8%a8%d8%b4%d8%b1%d8%a9-%d9%88%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%ac%d8%b3%d9%85\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d8%b9%d9%86%d8%a7%d9%8a%d8%a9-%d9%85%d8%aa%d8%ae%d8%b5%d8%b5%d8%a9\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Soins-Specifiques.jpg\" alt=\"\u0639\u0646\u0627\u064a\u0629 \u0645\u062a\u062e\u0635\u0635\u0629\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"%d8%b9%d9%86%d8%a7%d9%8a%d8%a9-%d9%85%d8%aa%d8%ae%d8%b5%d8%b5%d8%a9\">\u0639\u0646\u0627\u064a\u0629 \u0645\u062a\u062e\u0635\u0635\u0629<\/h2><p>\u0627\u0633\u062a\u0647\u062f\u0641\u064a \u0627\u062d\u062a\u064a\u0627\u062c\u0627\u062a\u0643 \u0627\u0644\u062e\u0627\u0635\u0629 \u0645\u0639 \u0645\u062c\u0645\u0648\u0639\u062a\u0646\u0627 \u0645\u0646 \u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0627\u0644\u062e\u0627\u0635\u0629: \u062a\u0631\u0643\u064a\u0628\u0627\u062a \u062e\u0628\u064a\u0631\u0629 \u0644\u0639\u0644\u0627\u062c \u0648\u062a\u0647\u062f\u0626\u0629 \u0648\u062a\u062d\u0633\u064a\u0646 \u0643\u0644 \u0646\u0648\u0639 \u0645\u0646 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0628\u0634\u0631\u0629 \u0623\u0648 \u0627\u0644\u0634\u0639\u0631.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d8%b9%d9%86%d8%a7%d9%8a%d8%a9-%d9%85%d8%aa%d8%ae%d8%b5%d8%b5%d8%a9\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d9%85%d8%b2%d9%8a%d9%84-%d8%a7%d9%84%d8%b9%d8%b1%d9%82-%d8%b1%d9%88%d9%84-%d8%a3%d9%88%d9%86-%d9%88%d8%b9%d8%b5%d8%a7\/\" class=\"bloc-categorie-produit\"><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"%d9%85%d8%b2%d9%8a%d9%84-%d8%a7%d9%84%d8%b9%d8%b1%d9%82-%d8%b1%d9%88%d9%84-%d8%a3%d9%88%d9%86-%d9%88%d8%b9%d8%b5%d8%a7\">\u0645\u0632\u064a\u0644 \u0627\u0644\u0639\u0631\u0642 \u0631\u0648\u0644 \u0623\u0648\u0646 \u0648\u0639\u0635\u0627<\/h2><p>\u062a\u0648\u0641\u0631 \u0623\u0639\u0648\u0627\u062f \u062f\u0648\u0644\u0644\u064a \u0627\u0644\u0639\u0645\u0644\u064a\u0629 \u0648\u0627\u0644\u0641\u0639\u0627\u0644\u0629 \u062a\u0637\u0628\u064a\u0642\u064b\u0627 \u0639\u0645\u0644\u064a\u064b\u0627 \u0648\u0641\u0639\u0627\u0644\u064b\u0627 \u0648\u0645\u0648\u062c\u0647\u064b\u0627 \u0648\u0635\u062d\u064a\u064b\u0627 \u0648\u0645\u062a\u0646\u0642\u0644\u064b\u0627. \u0644\u0628\u0634\u0631\u0629 \u0646\u0642\u064a\u0629 \u0648\u0645\u062d\u0645\u064a\u0629 \u0648\u0645\u0639\u062a\u0646\u0649 \u0628\u0647\u0627 \u062c\u064a\u062f\u064b\u0627 \u0623\u064a\u0646\u0645\u0627 \u0643\u0646\u062a\u0650.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d9%85%d8%b2%d9%8a%d9%84-%d8%a7%d9%84%d8%b9%d8%b1%d9%82-%d8%b1%d9%88%d9%84-%d8%a3%d9%88%d9%86-%d9%88%d8%b9%d8%b5%d8%a7\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><a href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d9%85%d8%b2%d9%8a%d9%84%d8%a7%d8%aa-%d8%a7%d9%84%d8%b9%d8%b1%d9%82\/\" class=\"bloc-categorie-produit\"><div class=\"image-categorie\"><img decoding=\"async\" src=\"http:\/\/dev.alcomnet.com\/cosimad\/wp-content\/uploads\/2025\/06\/Deodorants.png\" alt=\"\u0645\u0632\u064a\u0644\u0627\u062a \u0627\u0644\u0639\u0631\u0642\"><\/div><div class=\"categorie-produit-content\"><div class=\"categorie-content\"><h2 id=\"%d9%85%d8%b2%d9%8a%d9%84%d8%a7%d8%aa-%d8%a7%d9%84%d8%b9%d8%b1%d9%82\">\u0645\u0632\u064a\u0644\u0627\u062a \u0627\u0644\u0639\u0631\u0642<\/h2><p>Une protection invisible, un vent de l\u00e9g\u00e8ret\u00e9 pure Nos d\u00e9odorants prennent soin de votre peau, sans compromis sur la douceur.<\/p><\/div><strong href=\"http:\/\/dev.alcomnet.com\/cosimad\/dev2\/categorie-produit\/%d9%85%d8%b2%d9%8a%d9%84%d8%a7%d8%aa-%d8%a7%d9%84%d8%b9%d8%b1%d9%82\/\" class=\"btn-link\">En savoir plus<\/strong><\/div><\/a><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Product ranges Accueil \/ Page<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1884","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/dev.alcomnet.com\/cosimad\/wp-json\/wp\/v2\/pages\/1884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/dev.alcomnet.com\/cosimad\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/dev.alcomnet.com\/cosimad\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/dev.alcomnet.com\/cosimad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/dev.alcomnet.com\/cosimad\/wp-json\/wp\/v2\/comments?post=1884"}],"version-history":[{"count":4,"href":"http:\/\/dev.alcomnet.com\/cosimad\/wp-json\/wp\/v2\/pages\/1884\/revisions"}],"predecessor-version":[{"id":1935,"href":"http:\/\/dev.alcomnet.com\/cosimad\/wp-json\/wp\/v2\/pages\/1884\/revisions\/1935"}],"wp:attachment":[{"href":"http:\/\/dev.alcomnet.com\/cosimad\/wp-json\/wp\/v2\/media?parent=1884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}